{"id":4933,"date":"2016-11-19T11:49:48","date_gmt":"2016-11-19T10:49:48","guid":{"rendered":"https:\/\/www.schmucknaegel.de\/es\/?p=4933"},"modified":"2016-11-23T16:51:00","modified_gmt":"2016-11-23T15:51:00","slug":"encaje-unas","status":"publish","type":"post","link":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/","title":{"rendered":"Encaje para u\u00f1as y piedras strass"},"content":{"rendered":"<div style=\"clear: both;\">\r\n<h2>Encaje para u\u00f1as y piedras strass &#8211; Instrucci\u00f3n para oto\u00f1o paso a paso.<\/h2> \r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg\" alt=\"Encaje para u\u00f1as y piedras strass\" width=\"418\" height=\"314\" class=\"alignleft size-full sn-img-content\" \/>\r\n<\/div>\r\n<div class=\"sn-anker-content\">\r\n<p>\u00cdndice<br \/><a href=\"#productos\">&bull; Preparaci\u00f3n &#8211; Necesitan<\/a><br \/><a href=\"#paso-1\">&bull; Paso 1: Esmalte transparente, pinzeta, tijras y<br \/> encaje en blanco<\/a><br \/><a href=\"#paso-2\">&bull; Paso 2: Esmalte de color rojo oscuro y<br \/> nail art liner de color negro<\/a><br \/><a href=\"#paso-3\">&bull; Paso 3: Esmalte transparente, spot-swirl y<br \/> piedras strass<\/a><br \/><a href=\"#paso-4\">&bull; Paso 4: Esmalte transparente<\/a><\/p><\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-0.jpg\" alt=\"Productos para motivo con encaje para u\u00f1as y piedras strass - Esmalte, Nail art liner, Encaje para u\u00f1as, Piedras strass, Spot-Swirl\" width=\"270\" height=\"360\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><strong id=\"productos\">Necesitan:<\/strong><br \/>1. Esmalte en \u00abRojo oscuro\u00bb<br \/>2. Nail art liner en \u00abNegro\u00bb<br \/>3. Tijeras<br \/>4. Esmalte transparente<br \/>5. Encaje en \u00abBlanco\u00bb<br \/>6. Piedras strass en \u00abRojo\u00bb<br \/>7. Pinzeta<br \/>8. Spot-Swirl<br \/><\/p><\/div>\r\n<\/div>\r\n<div class=\"sn-ad-content\">\r\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- sn-wp-1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4740760903033421\"\r\n     data-ad-slot=\"9447377554\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-1.jpg\" alt=\"Consejo: Le recomendamos empezar con el dedo pulgar\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><strong>Consejo:<\/strong><br \/>Le recomendamos empezar con el dedo pulgar, el tiene la m\u00e0s grande superficie para aplicar el motivo.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-2.jpg\" alt=\"Esmalte transparente\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><strong id=\"paso-1\">Paso 1: Esmalte transparente, la pinzeta, las tijeras y el encaje en blanco<\/strong><br \/>Pinte con el esmalte transparente desde el borde izquierdo hasta el borde derecho una l\u00ednea ancha, para fijar el encaje en blanco.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-3.jpg\" alt=\"Esmalte transparente\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- sn-wp-linkblock-1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:200px;height:90px\"\r\n     data-ad-client=\"ca-pub-4740760903033421\"\r\n     data-ad-slot=\"1865235158\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-4.jpg\" alt=\"Pinzeta y encaje blanco\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>Para la preparaci\u00f3n corte con las tijeras un pedazo del encaje blanco. Sujete el pedazo con la pinzeta, sit\u00fae ahora el encaje sobre el esmalte transparente h\u00famedo.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-5.jpg\" alt=\"Pinzeta y encaje blanco\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>Ahora apriete con la pinzeta toda la superficie del encaje.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-6.jpg\" alt=\"Pinzeta y encaje blanco\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-7.jpg\" alt=\"Pinzeta y encaje blanco\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-8.jpg\" alt=\"Nail Art Motivo 273\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>El resultado debe ser aproximadamente.<\/p><p><strong>Indicar:<\/strong><br \/>\r\nAntes de contin\u00faar con el paso 2 espere hasta que el esmalte transparente este seco.\r\n<\/p>\r\n<\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-9.jpg\" alt=\"Esmalte de color rojo oscuro\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><strong id=\"paso-2\">Paso 2: Esmalte de color rojo oscuro y el nail art liner en negro<\/strong><br \/>Pinte la superficie libre debajo del encaje con el esmalte de color rojo oscuro.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-10.jpg\" alt=\"Esmalte de color rojo oscuro\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- sn-wp-200x200 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:200px;height:200px\"\r\n     data-ad-client=\"ca-pub-4740760903033421\"\r\n     data-ad-slot=\"6559459956\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-11.jpg\" alt=\"Nail art liner en negro\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>Dibuje con el nail art liner en negro, en los bordes del encaje una l\u00ednea, como en las fotograf\u00edas.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-12.jpg\" alt=\"Nail art liner en negro\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><strong>Consejo:<\/strong><br \/>Antes de usar el nail art liner tiene que quitar del pincel la laca que sobre. A trav\u00e9s de eso podra dibujar una fina l\u00ednea.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-13.jpg\" alt=\"Nail Art Motivo 273\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>El motivo con encaje para u\u00f1as y piedras strass debe ser aproximadamente como en la foto.<\/p><p><strong>Indicar:<\/strong><br \/>\r\nAntes de contin\u00faar con el paso 3 espere hasta que el esmalte este seco.\r\n<\/p>\r\n<\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-14.jpg\" alt=\"Esmalte transparente\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><strong id=\"paso-3\">Paso 3: Esmalte transparente, spot-swirl y tres piedras strass en rojo<\/strong><br \/>Utilice el esmalte transparente, coloque tres gotas sobre el encaje blanco para fijar las piedras strass en rojo.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-15.jpg\" alt=\"Esmalte transparente\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- sn-wp-linkblock-1 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:200px;height:90px\"\r\n     data-ad-client=\"ca-pub-4740760903033421\"\r\n     data-ad-slot=\"1865235158\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-16.jpg\" alt=\"Esmalte transparente\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-17.jpg\" alt=\"Piedras strass en rojo y spot-swirl\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>Humedezca el spot-swirl y coja una piedra strass roja. Coloque la piedra en la gota del esmalte transparente h\u00famedo.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-18.jpg\" alt=\"Piedras strass en rojo y spot-swirl\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>Repita el proceso anterior para poner dos piedras strass en rojo m\u00e1s.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-19.jpg\" alt=\"Piedras strass en rojo y spot-swirl\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-20.jpg\" alt=\"Nail Art Motivo 273\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>El nail art motivo con encaje para u\u00f1as y piedras strass debe ser aproximadamente como en la foto.<\/p><p><strong>Indicar:<\/strong><br \/>\r\nAntes de contin\u00faar con el \u00faltimo paso espere hasta que el esmalte transparente este seco.\r\n<\/p>\r\n<\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-21.jpg\" alt=\"Al fin utilice el esmalte transparente\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p><strong id=\"paso-4\">Paso 4: Esmalte transparente<\/strong><br \/>Al fin utilice el esmalte transparente. Pinte con el toda la u\u00f1a.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-22.jpg\" alt=\"El esmalte transparente protege el motivo\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>El esmalte transparente protege el motivo y le da m\u00e0s brillo.<\/p><\/div>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273-23.jpg\" alt=\"Nail art motivo\" width=\"270\" height=\"203\" class=\"alignleft size-full sn-img-content\" \/>\r\n<div class=\"sn-text-content\">\r\n<p>Despues de secarse el esmalte transparente esta el nail art motivo con encaje para u\u00f1as y piedras strass terminado.<\/p><\/div>\r\n<\/div>\r\n<div class=\"sn-ad-content\">\r\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- sn-wp-linkblock-responsive -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4740760903033421\"\r\n     data-ad-slot=\"3246066758\"\r\n     data-ad-format=\"link\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<\/div>\r\n<div style=\"clear: both;\">\r\n<p><strong>Esperamos que la instrucci\u00f3n gratis le guste y nos alegraria si usted nos recomiende a sus amistades.<\/strong><\/p><p>Si tiene alguna propuesta de mejoramiento de la p\u00e1gina Web o de las instrucci\u00f3nes gratis, le rogamos de comentar no lo. Envianos una E-mail a <a href=\"javascript:DeCryptX('3s0r3r2r1v1f0s3w1b2B0s2e2j2o2w2e0k1o1b2g1h1f0l311e0e')\">p&#114;&#111;p&#117;e&#115;t&#97;&#64;&#115;&#99;&#104;&#109;&#117;&#99;kn&#97;e&#103;&#101;l&#46;&#100;&#101;<\/a>. Muchas gracias por su ayuda y mucha diverci\u00f3n al probar las instrucci\u00f3nes gratis.<\/p><p><strong>Una mirada admirativa le garantizamos!<\/strong><\/p><\/div>\r\n<div style=\"clear: both;\">\r\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.schmucknaegel.de\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg\" alt=\"Encaje para u\u00f1as y piedras strass\" width=\"418\" height=\"314\" class=\"alignleft size-full sn-img-content\" \/>\r\n<\/div>\r\n<div class=\"sn-anker-content\">\r\n<p>\u00cdndice<br \/><a href=\"#productos\">&bull; Preparaci\u00f3n &#8211; Necesitan<\/a><br \/><a href=\"#paso-1\">&bull; Paso 1: Esmalte transparente, pinzeta, tijras y<br \/> encaje en blanco<\/a><br \/><a href=\"#paso-2\">&bull; Paso 2: Esmalte de color rojo oscuro y<br \/> nail art liner de color negro<\/a><br \/><a href=\"#paso-3\">&bull; Paso 3: Esmalte transparente, spot-swirl y<br \/> piedras strass<\/a><br \/><a href=\"#paso-4\">&bull; Paso 4: Esmalte transparente<\/a><\/p><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8;border-radius:25%\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.schmucknaegel.de%2Fes%2Fencaje-unas%2F\" title=\"Compartir en Facebook\" aria-label=\"Compartir en Facebook\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\";border-radius:25%; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959;border-radius:25%\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.schmucknaegel.de%2Fes%2Fencaje-unas%2F&text=Encaje%20para%20u%C3%B1as%20y%20piedras%20strass\" title=\"Compartir en X\" aria-label=\"Compartir en X\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:25%; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18;border-radius:25%\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fwww.schmucknaegel.de%2Fes%2Fencaje-unas%2F&media=https%3A%2F%2Fwww.schmucknaegel.de%2Fes%2Fwp-content%2Fuploads%2Fsites%2F3%2F2016%2F04%2Fnailart-273.jpg&description=Encaje%20para%20u%C3%B1as%20y%20piedras%20strass\" title=\"Ahorrar en Pinterest\" aria-label=\"Ahorrar en Pinterest\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:25%; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button reddit shariff-nocustomcolor\" style=\"background-color:#ff5700;border-radius:25%\"><a href=\"https:\/\/www.reddit.com\/submit?url=https%3A%2F%2Fwww.schmucknaegel.de%2Fes%2Fencaje-unas%2F\" title=\"Compartir en Reddit\" aria-label=\"Compartir en Reddit\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:25%; background-color:#ff4500; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path fill=\"#ff4500\" d=\"M440.3 203.5c-15 0-28.2 6.2-37.9 15.9-35.7-24.7-83.8-40.6-137.1-42.3L293 52.3l88.2 19.8c0 21.6 17.6 39.2 39.2 39.2 22 0 39.7-18.1 39.7-39.7s-17.6-39.7-39.7-39.7c-15.4 0-28.7 9.3-35.3 22l-97.4-21.6c-4.9-1.3-9.7 2.2-11 7.1L246.3 177c-52.9 2.2-100.5 18.1-136.3 42.8-9.7-10.1-23.4-16.3-38.4-16.3-55.6 0-73.8 74.6-22.9 100.1-1.8 7.9-2.6 16.3-2.6 24.7 0 83.8 94.4 151.7 210.3 151.7 116.4 0 210.8-67.9 210.8-151.7 0-8.4-.9-17.2-3.1-25.1 49.9-25.6 31.5-99.7-23.8-99.7zM129.4 308.9c0-22 17.6-39.7 39.7-39.7 21.6 0 39.2 17.6 39.2 39.7 0 21.6-17.6 39.2-39.2 39.2-22 .1-39.7-17.6-39.7-39.2zm214.3 93.5c-36.4 36.4-139.1 36.4-175.5 0-4-3.5-4-9.7 0-13.7 3.5-3.5 9.7-3.5 13.2 0 27.8 28.5 120 29 149 0 3.5-3.5 9.7-3.5 13.2 0 4.1 4 4.1 10.2.1 13.7zm-.8-54.2c-21.6 0-39.2-17.6-39.2-39.2 0-22 17.6-39.7 39.2-39.7 22 0 39.7 17.6 39.7 39.7-.1 21.5-17.7 39.2-39.7 39.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee;border-radius:25%\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"M\u00e1s informaciones\" aria-label=\"M\u00e1s informaciones\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\";border-radius:25%; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>en rojo &#8211; Instrucci\u00f3n para oto\u00f1o paso a paso. Mucha diverci\u00f3n al probar!<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/\"><span>Leer mas<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>","protected":false},"author":1,"featured_media":3916,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23,12],"tags":[55,18,17,30,29],"class_list":["post-4933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-disenos-unas","category-otono","category-unas-francesas","tag-encaje-para-unas","tag-esmalte","tag-nail-art-liner","tag-piedras-strass","tag-spot-swirl"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encaje para u\u00f1as y piedras strass - Dise\u00f1os de u\u00f1as<\/title>\n<meta name=\"description\" content=\"Encaje para u\u00f1as y piedras strass en rojo - Instrucci\u00f3n para oto\u00f1o paso a paso. Mucha diverci\u00f3n al probar las instrucci\u00f3nes gratis!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encaje para u\u00f1as y piedras strass - Dise\u00f1os de u\u00f1as\" \/>\n<meta property=\"og:description\" content=\"Encaje para u\u00f1as y piedras strass en rojo - Instrucci\u00f3n para oto\u00f1o paso a paso. Mucha diverci\u00f3n al probar las instrucci\u00f3nes gratis!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/\" \/>\n<meta property=\"og:site_name\" content=\"Dise\u00f1os de u\u00f1as\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unas.decoradas\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-19T10:49:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-23T15:51:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schmucknaegel.de\/es\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"418\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Make it Smart e.K.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@schmucknaegel\" \/>\n<meta name=\"twitter:site\" content=\"@schmucknaegel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Make it Smart e.K.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/\"},\"author\":{\"name\":\"Make it Smart e.K.\",\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/#\\\/schema\\\/person\\\/74931f02bc875223464efd8461cdb7db\"},\"headline\":\"Encaje para u\u00f1as y piedras strass\",\"datePublished\":\"2016-11-19T10:49:48+00:00\",\"dateModified\":\"2016-11-23T15:51:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/\"},\"wordCount\":578,\"image\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/nailart-273.jpg\",\"keywords\":[\"Encaje para u\u00f1as\",\"Esmalte\",\"Nail art liner\",\"Piedras strass\",\"Spot-Swirl\"],\"articleSection\":[\"Dise\u00f1os de u\u00f1as\",\"Oto\u00f1o\",\"U\u00f1as francesas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/\",\"url\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/\",\"name\":\"Encaje para u\u00f1as y piedras strass - Dise\u00f1os de u\u00f1as\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/nailart-273.jpg\",\"datePublished\":\"2016-11-19T10:49:48+00:00\",\"dateModified\":\"2016-11-23T15:51:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/#\\\/schema\\\/person\\\/74931f02bc875223464efd8461cdb7db\"},\"description\":\"Encaje para u\u00f1as y piedras strass en rojo - Instrucci\u00f3n para oto\u00f1o paso a paso. Mucha diverci\u00f3n al probar las instrucci\u00f3nes gratis!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/nailart-273.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/04\\\/nailart-273.jpg\",\"width\":418,\"height\":314,\"caption\":\"Encaje para u\u00f1as y piedras strass\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/encaje-unas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encaje para u\u00f1as y piedras strass\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/\",\"name\":\"Dise\u00f1os de u\u00f1as\",\"description\":\"para u\u00f1as hermosas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schmucknaegel.de\\\/es\\\/#\\\/schema\\\/person\\\/74931f02bc875223464efd8461cdb7db\",\"name\":\"Make it Smart e.K.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db8bd55e7885b51d4731012fec0100f206a775ebb6fc62070543f10f3e9f7af1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db8bd55e7885b51d4731012fec0100f206a775ebb6fc62070543f10f3e9f7af1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db8bd55e7885b51d4731012fec0100f206a775ebb6fc62070543f10f3e9f7af1?s=96&d=mm&r=g\",\"caption\":\"Make it Smart e.K.\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encaje para u\u00f1as y piedras strass - Dise\u00f1os de u\u00f1as","description":"Encaje para u\u00f1as y piedras strass en rojo - Instrucci\u00f3n para oto\u00f1o paso a paso. Mucha diverci\u00f3n al probar las instrucci\u00f3nes gratis!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/","og_locale":"es_ES","og_type":"article","og_title":"Encaje para u\u00f1as y piedras strass - Dise\u00f1os de u\u00f1as","og_description":"Encaje para u\u00f1as y piedras strass en rojo - Instrucci\u00f3n para oto\u00f1o paso a paso. Mucha diverci\u00f3n al probar las instrucci\u00f3nes gratis!","og_url":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/","og_site_name":"Dise\u00f1os de u\u00f1as","article_publisher":"https:\/\/www.facebook.com\/unas.decoradas\/","article_published_time":"2016-11-19T10:49:48+00:00","article_modified_time":"2016-11-23T15:51:00+00:00","og_image":[{"width":418,"height":314,"url":"https:\/\/www.schmucknaegel.de\/es\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg","type":"image\/jpeg"}],"author":"Make it Smart e.K.","twitter_card":"summary_large_image","twitter_creator":"@schmucknaegel","twitter_site":"@schmucknaegel","twitter_misc":{"Escrito por":"Make it Smart e.K.","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/#article","isPartOf":{"@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/"},"author":{"name":"Make it Smart e.K.","@id":"https:\/\/www.schmucknaegel.de\/es\/#\/schema\/person\/74931f02bc875223464efd8461cdb7db"},"headline":"Encaje para u\u00f1as y piedras strass","datePublished":"2016-11-19T10:49:48+00:00","dateModified":"2016-11-23T15:51:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/"},"wordCount":578,"image":{"@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schmucknaegel.de\/es\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg","keywords":["Encaje para u\u00f1as","Esmalte","Nail art liner","Piedras strass","Spot-Swirl"],"articleSection":["Dise\u00f1os de u\u00f1as","Oto\u00f1o","U\u00f1as francesas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/","url":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/","name":"Encaje para u\u00f1as y piedras strass - Dise\u00f1os de u\u00f1as","isPartOf":{"@id":"https:\/\/www.schmucknaegel.de\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/#primaryimage"},"image":{"@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schmucknaegel.de\/es\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg","datePublished":"2016-11-19T10:49:48+00:00","dateModified":"2016-11-23T15:51:00+00:00","author":{"@id":"https:\/\/www.schmucknaegel.de\/es\/#\/schema\/person\/74931f02bc875223464efd8461cdb7db"},"description":"Encaje para u\u00f1as y piedras strass en rojo - Instrucci\u00f3n para oto\u00f1o paso a paso. Mucha diverci\u00f3n al probar las instrucci\u00f3nes gratis!","breadcrumb":{"@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/#primaryimage","url":"https:\/\/www.schmucknaegel.de\/es\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg","contentUrl":"https:\/\/www.schmucknaegel.de\/es\/wp-content\/uploads\/sites\/3\/2016\/04\/nailart-273.jpg","width":418,"height":314,"caption":"Encaje para u\u00f1as y piedras strass"},{"@type":"BreadcrumbList","@id":"https:\/\/www.schmucknaegel.de\/es\/encaje-unas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.schmucknaegel.de\/es\/"},{"@type":"ListItem","position":2,"name":"Encaje para u\u00f1as y piedras strass"}]},{"@type":"WebSite","@id":"https:\/\/www.schmucknaegel.de\/es\/#website","url":"https:\/\/www.schmucknaegel.de\/es\/","name":"Dise\u00f1os de u\u00f1as","description":"para u\u00f1as hermosas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schmucknaegel.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.schmucknaegel.de\/es\/#\/schema\/person\/74931f02bc875223464efd8461cdb7db","name":"Make it Smart e.K.","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/db8bd55e7885b51d4731012fec0100f206a775ebb6fc62070543f10f3e9f7af1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/db8bd55e7885b51d4731012fec0100f206a775ebb6fc62070543f10f3e9f7af1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db8bd55e7885b51d4731012fec0100f206a775ebb6fc62070543f10f3e9f7af1?s=96&d=mm&r=g","caption":"Make it Smart e.K."}}]}},"_links":{"self":[{"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/posts\/4933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/comments?post=4933"}],"version-history":[{"count":0,"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/posts\/4933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/media\/3916"}],"wp:attachment":[{"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/media?parent=4933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/categories?post=4933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schmucknaegel.de\/es\/wp-json\/wp\/v2\/tags?post=4933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}